{"id":6240,"date":"2021-01-21T09:25:00","date_gmt":"2021-01-21T08:25:00","guid":{"rendered":"http:\/\/med-design.net\/wp-content\/uploads\/2021\/01\/Marketing_2.jpg"},"modified":"2021-03-10T10:06:36","modified_gmt":"2021-03-10T09:06:36","slug":"host_boone-11","status":"inherit","type":"attachment","link":"http:\/\/med-design.net\/en\/2021\/01\/19\/case-study-bowa\/host_boone-11\/","title":{"rendered":"B\u00fchler Bowa"},"author":5,"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","meta":[],"class_list":["post-6240","attachment","type-attachment","status-inherit","hentry"],"description":{"rendered":"<p class=\"attachment\"><a href='http:\/\/med-design.net\/wp-content\/uploads\/2021\/01\/Marketing_2.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"169\" src=\"http:\/\/med-design.net\/wp-content\/uploads\/2021\/01\/Marketing_2-300x169.jpg\" class=\"attachment-medium size-medium\" alt=\"B\u00fchler Interview\" srcset=\"http:\/\/med-design.net\/wp-content\/uploads\/2021\/01\/Marketing_2-300x169.jpg 300w, http:\/\/med-design.net\/wp-content\/uploads\/2021\/01\/Marketing_2-1024x576.jpg 1024w, http:\/\/med-design.net\/wp-content\/uploads\/2021\/01\/Marketing_2-768x432.jpg 768w, http:\/\/med-design.net\/wp-content\/uploads\/2021\/01\/Marketing_2-1536x864.jpg 1536w, http:\/\/med-design.net\/wp-content\/uploads\/2021\/01\/Marketing_2-1170x658.jpg 1170w, http:\/\/med-design.net\/wp-content\/uploads\/2021\/01\/Marketing_2-560x315.jpg 560w, http:\/\/med-design.net\/wp-content\/uploads\/2021\/01\/Marketing_2.jpg 1920w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n<p>B\u00fchler Bowa, Interview, ARC, Dreharbeiten, Show, Film<\/p>\n"},"caption":{"rendered":"<p>B\u00fchler Bowa, Interview, ARC, Dreharbeiten, Show, Film<\/p>\n"},"alt_text":"B\u00fchler Interview","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":1920,"height":1080,"file":"2021\/01\/Marketing_2.jpg","sizes":{"medium":{"file":"Marketing_2-300x169.jpg","width":300,"height":169,"mime_type":"image\/jpeg","source_url":"http:\/\/med-design.net\/wp-content\/uploads\/2021\/01\/Marketing_2-300x169.jpg"},"large":{"file":"Marketing_2-1024x576.jpg","width":1024,"height":576,"mime_type":"image\/jpeg","source_url":"http:\/\/med-design.net\/wp-content\/uploads\/2021\/01\/Marketing_2-1024x576.jpg"},"thumbnail":{"file":"Marketing_2-150x150.jpg","width":150,"height":150,"mime_type":"image\/jpeg","source_url":"http:\/\/med-design.net\/wp-content\/uploads\/2021\/01\/Marketing_2-150x150.jpg"},"medium_large":{"file":"Marketing_2-768x432.jpg","width":768,"height":432,"mime_type":"image\/jpeg","source_url":"http:\/\/med-design.net\/wp-content\/uploads\/2021\/01\/Marketing_2-768x432.jpg"},"1536x1536":{"file":"Marketing_2-1536x864.jpg","width":1536,"height":864,"mime_type":"image\/jpeg","source_url":"http:\/\/med-design.net\/wp-content\/uploads\/2021\/01\/Marketing_2-1536x864.jpg"},"grve-image-extrasmall-square":{"file":"Marketing_2-80x80.jpg","width":80,"height":80,"mime_type":"image\/jpeg","source_url":"http:\/\/med-design.net\/wp-content\/uploads\/2021\/01\/Marketing_2-80x80.jpg"},"grve-image-large-rect-horizontal":{"file":"Marketing_2-1170x658.jpg","width":1170,"height":658,"mime_type":"image\/jpeg","source_url":"http:\/\/med-design.net\/wp-content\/uploads\/2021\/01\/Marketing_2-1170x658.jpg"},"grve-image-small-square":{"file":"Marketing_2-560x560.jpg","width":560,"height":560,"mime_type":"image\/jpeg","source_url":"http:\/\/med-design.net\/wp-content\/uploads\/2021\/01\/Marketing_2-560x560.jpg"},"grve-image-small-rect-horizontal":{"file":"Marketing_2-560x315.jpg","width":560,"height":315,"mime_type":"image\/jpeg","source_url":"http:\/\/med-design.net\/wp-content\/uploads\/2021\/01\/Marketing_2-560x315.jpg"},"grve-image-medium-rect-vertical":{"file":"Marketing_2-560x1080.jpg","width":560,"height":1080,"mime_type":"image\/jpeg","source_url":"http:\/\/med-design.net\/wp-content\/uploads\/2021\/01\/Marketing_2-560x1080.jpg"},"grve-image-medium-rect-horizontal":{"file":"Marketing_2-1120x560.jpg","width":1120,"height":560,"mime_type":"image\/jpeg","source_url":"http:\/\/med-design.net\/wp-content\/uploads\/2021\/01\/Marketing_2-1120x560.jpg"},"grve-image-medium-square":{"file":"Marketing_2-1120x1080.jpg","width":1120,"height":1080,"mime_type":"image\/jpeg","source_url":"http:\/\/med-design.net\/wp-content\/uploads\/2021\/01\/Marketing_2-1120x1080.jpg"},"full":{"file":"Marketing_2.jpg","width":1920,"height":1080,"mime_type":"image\/jpeg","source_url":"http:\/\/med-design.net\/wp-content\/uploads\/2021\/01\/Marketing_2.jpg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"Host_Boone","orientation":"0","keywords":[]}},"post":6078,"source_url":"http:\/\/med-design.net\/wp-content\/uploads\/2021\/01\/Marketing_2.jpg","_links":{"self":[{"href":"http:\/\/med-design.net\/en\/wp-json\/wp\/v2\/media\/6240","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/med-design.net\/en\/wp-json\/wp\/v2\/media"}],"about":[{"href":"http:\/\/med-design.net\/en\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"http:\/\/med-design.net\/en\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"http:\/\/med-design.net\/en\/wp-json\/wp\/v2\/comments?post=6240"}],"wp:attached-to":[{"embeddable":true,"post_type":"post","id":6078,"href":"http:\/\/med-design.net\/en\/wp-json\/wp\/v2\/posts\/6078"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}